{"id":140,"date":"2018-03-15T08:31:22","date_gmt":"2018-03-15T08:31:22","guid":{"rendered":"http:\/\/themes.radiantthemes.com\/constructionpress\/checkout\/"},"modified":"2018-03-15T08:31:22","modified_gmt":"2018-03-15T08:31:22","slug":"checkout","status":"publish","type":"page","link":"https:\/\/medentis.ro\/de\/checkout\/","title":{"rendered":"Checkout"},"content":{"rendered":"<p>[woocommerce_checkout]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[woocommerce_checkout]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-140","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/medentis.ro\/de\/wp-json\/wp\/v2\/pages\/140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medentis.ro\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/medentis.ro\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/medentis.ro\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/medentis.ro\/de\/wp-json\/wp\/v2\/comments?post=140"}],"version-history":[{"count":0,"href":"https:\/\/medentis.ro\/de\/wp-json\/wp\/v2\/pages\/140\/revisions"}],"wp:attachment":[{"href":"https:\/\/medentis.ro\/de\/wp-json\/wp\/v2\/media?parent=140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}